{"id":5764,"date":"2023-06-21T07:11:20","date_gmt":"2023-06-21T07:11:20","guid":{"rendered":"https:\/\/borgel.com\/?post_type=portfolio&#038;p=5764"},"modified":"2023-06-26T11:54:49","modified_gmt":"2023-06-26T11:54:49","slug":"data-center-10","status":"publish","type":"portfolio","link":"https:\/\/borgel.com\/de\/portfolio\/item\/data-center-10","title":{"rendered":"Rechenzentrum - BE010"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5764\" class=\"elementor elementor-5764\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4fe754 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f4fe754\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c029c1a\" data-id=\"c029c1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e14463 elementor-widget elementor-widget-larson-intro\" data-id=\"2e14463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"larson-intro.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<article class=\"article\">\n\t        <header class=\"article__header\">\n\t          <div class=\"container\">\n\t            \t            <h1 class=\"article__heading heading heading--size-large\">\n\t            \t<span >\n\t\t\t\t\t\t<p>Datenzentrum<\/p>\t\t\t\t\t<\/span>\n\t            <\/h1>\n\t            \t            \t            <div class=\"article__header-text\">\n\t            \t<span >\n\t\t\t\t\t\t<p>BE010 - Deutschland\/Hessen<\/p>\t\t\t\t\t<\/span>\n\t            <\/div>\n\t            \t          <\/div>\n\t        <\/header>\n\t        \t    <\/article>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5f2d87 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c5f2d87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a245d6\" data-id=\"9a245d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0267eb elementor-widget elementor-widget-larson-project-image\" data-id=\"b0267eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"larson-project-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t<div class=\"article__project-hero\" data-aos=\"fade\">\n          <img decoding=\"async\" src=\"https:\/\/borgel.com\/wp-content\/uploads\/2023\/04\/18-data-hall-36-symbol-7993-1-1920x1080.jpg\" alt=\"\" \/>\n        <\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbc5d63 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cbc5d63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3777a6 elementor-widget elementor-widget-larson-project-details\" data-id=\"e3777a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"larson-project-details.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"article__main container\">\n\t\t            <ul class=\"article__project-meta project-meta\" data-aos=\"fade\">\n          \t            <li class=\"project-meta__item\">\n                            <div class=\"project-meta__item-title\">\n              \t<span >\n\t\t\t\t\tKunde\t\t\t\t<\/span>\n              <\/div>\n                                          <div class=\"project-meta__item-text\">\n              \t<span >\n\t\t\t\t\tunterliegt dem Datenschutz\t\t\t\t<\/span>\n              <\/div>\n                          <\/li>\n                        <li class=\"project-meta__item\">\n                            <div class=\"project-meta__item-title\">\n              \t<span >\n\t\t\t\t\tFertigstellung\t\t\t\t<\/span>\n              <\/div>\n                                          <div class=\"project-meta__item-text\">\n              \t<span >\n\t\t\t\t\t2023\t\t\t\t<\/span>\n              <\/div>\n                          <\/li>\n                        <li class=\"project-meta__item\">\n                            <div class=\"project-meta__item-title\">\n              \t<span >\n\t\t\t\t\tProjekttyp\t\t\t\t<\/span>\n              <\/div>\n                                          <div class=\"project-meta__item-text\">\n              \t<span >\n\t\t\t\t\tRechenzentrum, BE010\t\t\t\t<\/span>\n              <\/div>\n                          <\/li>\n                        <li class=\"project-meta__item\">\n                            <div class=\"project-meta__item-title\">\n              \t<span >\n\t\t\t\t\tStandort\t\t\t\t<\/span>\n              <\/div>\n                                          <div class=\"project-meta__item-text\">\n              \t<span >\n\t\t\t\t\tDeutschland\/Hessen\t\t\t\t<\/span>\n              <\/div>\n                          <\/li>\n                      <\/ul>\n                  <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99558a3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"99558a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b41ef85 elementor-widget elementor-widget-toggle\" data-id=\"b41ef85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mehr \u00fcber Dienstleistungen Borgel Elementbau<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1881\"><ul><li><p>Dach:<br \/>\u2013 2265 m\u00b2 Dachabdichtung mit Entw\u00e4sserung<br \/>\u2013 5 Rauchwarnanlagen (RWA\u00b4s)<br \/>\u2013 455 m\u00b2 Wartungswege auf dem Dach<\/p><\/li><li><p>W\u00e4nde:<br \/>\u2013 ca. 3000 m\u00b2 Streckmetall-Fassade<br \/>\u2013 ca. 590 m horizontale Alufassadeblende<br \/>\u2013 ca. 13 0m\u00b2 Alucobond-Fassade<br \/>\u2013 ca. 920 m\u00b2 Lamellenwand-Fassade<br \/>\u2013 ca. 525 m\u00b2 Edelathalnetz-Fassade in RC3<\/p><\/li><li><p>Sonstige:<br \/>\u2013 26 Druckentlastunugsklappen mit Wetterschutzgitter teilweise in RC3<br \/>\u2013 95 Entrauchungsfenster teilweise in RC3<br \/>\u2013 1 Aluminium-Fenster und 3 T\u00fcren in RC3<br \/>\u2013 14 Stahlt\u00fcren<br \/>\u2013 1 Rolltor in RC3<\/p><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7e76b3 elementor-widget elementor-widget-spacer\" data-id=\"b7e76b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0dc0d82 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0dc0d82\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5528f88 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5528f88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d53a8c elementor-widget elementor-widget-heading\" data-id=\"2d53a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neueste Projekte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84e15db e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"84e15db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c255966 elementor-widget elementor-widget-larson-portfolio\" data-id=\"c255966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"larson-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\t\t<div class=\"article__main container\">\n\n                    <ul class=\"projects-masonry row __js_projects-grid\">\n          \t<li class=\"grid-sizer\"><\/li>\n          \t\n\n<li class=\"projects-masonry__item col-12 col-md-6 col-xl-4 __js_masonry-item __js_data-centers\">\n  <a class=\"card card--small card--masonry\" href=\"https:\/\/borgel.com\/de\/portfolio\/item\/data-center-01\">\n        <div class=\"card__image\">\n      <img decoding=\"async\" src=\"https:\/\/borgel.com\/wp-content\/uploads\/2023\/06\/neu1@4x-900x900.png\" alt=\"Data Center &#8211; BE001\" \/>\n    <\/div>\n        <div class=\"card__content\">\n            <h3 class=\"card__heading\">\n      \tRechenzentrum - BE001      <\/h3>\n                  <div class=\"card__text\">\n      \tDatenzentrum \r\n      <\/div>\n            <div class=\"card__bottom\">\n        <span class=\"card__link\">\n          Siehe Projekt          <svg width=\"20\" height=\"20\">\n            <use xlink:href=\"#chevron-right\"><\/use>\n          <\/svg>\n        <\/span>\n      <\/div>\n    <\/div>\n  <\/a>\n<\/li>\n\n<li class=\"projects-masonry__item col-12 col-md-6 col-xl-4 __js_masonry-item __js_data-centers\">\n  <a class=\"card card--small card--masonry\" href=\"https:\/\/borgel.com\/de\/portfolio\/item\/data-center-02\">\n        <div class=\"card__image\">\n      <img decoding=\"async\" src=\"https:\/\/borgel.com\/wp-content\/uploads\/2023\/06\/neu@4x-900x900.png\" alt=\"Data Center &#8211; BE002\" \/>\n    <\/div>\n        <div class=\"card__content\">\n            <h3 class=\"card__heading\">\n      \tRechenzentrum - BE002      <\/h3>\n                  <div class=\"card__text\">\n      \tDatenzentrum \r\n      <\/div>\n            <div class=\"card__bottom\">\n        <span class=\"card__link\">\n          Siehe Projekt          <svg width=\"20\" height=\"20\">\n            <use xlink:href=\"#chevron-right\"><\/use>\n          <\/svg>\n        <\/span>\n      <\/div>\n    <\/div>\n  <\/a>\n<\/li>\n\n<li class=\"projects-masonry__item col-12 col-md-6 col-xl-4 __js_masonry-item __js_data-centers\">\n  <a class=\"card card--small card--masonry\" href=\"https:\/\/borgel.com\/de\/portfolio\/item\/data-center-03\">\n        <div class=\"card__image\">\n      <img decoding=\"async\" src=\"https:\/\/borgel.com\/wp-content\/uploads\/2023\/06\/neu3@4x-900x900.png\" alt=\"Data Center &#8211; BE003\" \/>\n    <\/div>\n        <div class=\"card__content\">\n            <h3 class=\"card__heading\">\n      \tRechenzentrum - BE003      <\/h3>\n                  <div class=\"card__text\">\n      \tDatenzentrum \r\n      <\/div>\n            <div class=\"card__bottom\">\n        <span class=\"card__link\">\n          Siehe Projekt          <svg width=\"20\" height=\"20\">\n            <use xlink:href=\"#chevron-right\"><\/use>\n          <\/svg>\n        <\/span>\n      <\/div>\n    <\/div>\n  <\/a>\n<\/li>          <\/ul>\n\n          \t   \t\t<div class=\"pager\">\n\t    \t\t<span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/page\/2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/page\/3\">3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/page\/4\">4<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/page\/2\">Weiter<\/a>\t\t\t<\/div>\n\t\t\t\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"featured_media":5790,"menu_order":0,"template":"template-elementor-default.php","portfolio_categories":[21],"class_list":["post-5764","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_categories-data-centers"],"acf":[],"_links":{"self":[{"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":8,"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/revisions"}],"predecessor-version":[{"id":5974,"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio\/5764\/revisions\/5974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/media\/5790"}],"wp:attachment":[{"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/media?parent=5764"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/borgel.com\/de\/wp-json\/wp\/v2\/portfolio_categories?post=5764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}